{"id":1185,"date":"2017-01-10T08:25:29","date_gmt":"2017-01-10T08:25:29","guid":{"rendered":"http:\/\/www.nebrija.com\/medios\/nebrijaglobalcampus\/?p=1185"},"modified":"2017-01-10T08:25:29","modified_gmt":"2017-01-10T08:25:29","slug":"bienvenids-al-2017","status":"publish","type":"post","link":"https:\/\/www.nebrija.com\/medios\/nebrijaglobalcampus\/2017\/01\/10\/bienvenids-al-2017\/","title":{"rendered":"Bienvenid@s al 2017"},"content":{"rendered":"<p>Estrenamos calendario. 365 oportunidades para crecer, aprender, equivocarse, triunfar, retomar, decidir, cambiar, intentar&#8230; Todo est\u00e1 por hacer. Y m\u00e1s en el \u00e1mbito de la formaci\u00f3n y el aprendizaje:<\/p>\n<p style=\"text-align: center\"><i>\u00abLos analfabetos del siglo XXI no ser\u00e1n aquellos que no sepan leer y escribir,<\/i><\/p>\n<p style=\"text-align: center\"><em>sino aquellos que no sepan aprender, desaprender y reaprender\u00bb, <\/em>Herbert Gerjuoy.<\/p>\n<p>&nbsp;<\/p>\n<p>El mundo va cada vez m\u00e1s deprisa, est\u00e1 lleno de complejidades y tambi\u00e9n hay gran cantidad de retos por delante. La decisi\u00f3n es s\u00f3lo tuya. \u00bfDispuest@ a sacarle partido?<\/p>\n<div class=\"arve aligncenter\" data-mode=\"normal\" data-provider=\"vimeo\" id=\"arve-vimeo-1962935846a04ff285a544524232735\" style=\"max-width:400px;\">\n<span class=\"arve-inner\">\n<span class=\"arve-embed arve-embed--has-aspect-ratio\">\n<span class=\"arve-ar\" style=\"padding-top:56.250000%\"><\/span><iframe loading=\"lazy\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen class=\"arve-iframe fitvidsignore\" data-arve=\"arve-vimeo-1962935846a04ff285a544524232735\" data-src-no-ap=\"https:\/\/player.vimeo.com\/video\/196293584?dnt=1&amp;html5=1&amp;title=0&amp;byline=0&amp;portrait=0&amp;autoplay=0\" frameborder=\"0\" height=\"225\" sandbox=\"allow-scripts allow-same-origin allow-presentation allow-popups allow-popups-to-escape-sandbox allow-forms\" scrolling=\"no\" src=\"https:\/\/player.vimeo.com\/video\/196293584?dnt=1&#038;html5=1&#038;title=0&#038;byline=0&#038;portrait=0&#038;autoplay=0\" width=\"400\"><\/iframe>\n\n<\/span>\n\n<\/span>\n<script type=\"application\/ld+json\">{\"@context\":\"http:\\\/\\\/schema.org\\\/\",\"@id\":\"https:\\\/\\\/www.nebrija.com\\\/medios\\\/nebrijaglobalcampus\\\/2017\\\/01\\\/10\\\/bienvenids-al-2017\\\/#arve-vimeo-1962935846a04ff285a544524232735\",\"type\":\"VideoObject\",\"embedURL\":\"https:\\\/\\\/player.vimeo.com\\\/video\\\/196293584?dnt=1&html5=1&title=0&byline=0&portrait=0&autoplay=0\"}<\/script>\n<\/div>\n\n<p>&nbsp;<\/p>\n<p>Bienvenid@ y&#8230; \u00a1Feliz 2017!<\/p>\n<p>&nbsp;<\/p>\n<p><em><strong>Global Campus Nebrija<\/strong><\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estrenamos calendario. 365 oportunidades para crecer, aprender, equivocarse, triunfar, retomar, decidir, cambiar, intentar&#8230; Todo est\u00e1 por hacer. Y m\u00e1s en el \u00e1mbito de la formaci\u00f3n y el aprendizaje: \u00abLos analfabetos del siglo XXI no ser\u00e1n aquellos que no sepan leer y escribir, sino aquellos que no sepan aprender, desaprender y reaprender\u00bb, Herbert Gerjuoy. &nbsp; El [&hellip;]<\/p>\n","protected":false},"author":97,"featured_media":1191,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[9,1],"tags":[549,550,54],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Bienvenid@s al 2017 - Global Campus Nebrija<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.nebrija.com\/medios\/nebrijaglobalcampus\/2017\/01\/10\/bienvenids-al-2017\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bienvenid@s al 2017 - Global Campus Nebrija\" \/>\n<meta property=\"og:description\" content=\"Estrenamos calendario. 365 oportunidades para crecer, aprender, equivocarse, triunfar, retomar, decidir, cambiar, intentar&#8230; Todo est\u00e1 por hacer. Y m\u00e1s en el \u00e1mbito de la formaci\u00f3n y el aprendizaje: \u00abLos analfabetos del siglo XXI no ser\u00e1n aquellos que no sepan leer y escribir, sino aquellos que no sepan aprender, desaprender y reaprender\u00bb, Herbert Gerjuoy. &nbsp; El [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.nebrija.com\/medios\/nebrijaglobalcampus\/2017\/01\/10\/bienvenids-al-2017\/\" \/>\n<meta property=\"og:site_name\" content=\"Global Campus Nebrija\" \/>\n<meta property=\"article:published_time\" content=\"2017-01-10T08:25:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.nebrija.com\/medios\/nebrijaglobalcampus\/wp-content\/uploads\/sites\/31\/2017\/01\/shutterstock_538443043b.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"4584\" \/>\n\t<meta property=\"og:image:height\" content=\"3690\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mgarcisa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mgarcisa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.nebrija.com\/medios\/nebrijaglobalcampus\/2017\/01\/10\/bienvenids-al-2017\/\",\"url\":\"https:\/\/www.nebrija.com\/medios\/nebrijaglobalcampus\/2017\/01\/10\/bienvenids-al-2017\/\",\"name\":\"Bienvenid@s al 2017 - Global Campus Nebrija\",\"isPartOf\":{\"@id\":\"https:\/\/www.nebrija.com\/medios\/nebrijaglobalcampus\/#website\"},\"datePublished\":\"2017-01-10T08:25:29+00:00\",\"dateModified\":\"2017-01-10T08:25:29+00:00\",\"author\":{\"@id\":\"https:\/\/www.nebrija.com\/medios\/nebrijaglobalcampus\/#\/schema\/person\/0fa46cb03c7e07b210c31383337aa6ee\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.nebrija.com\/medios\/nebrijaglobalcampus\/2017\/01\/10\/bienvenids-al-2017\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.nebrija.com\/medios\/nebrijaglobalcampus\/2017\/01\/10\/bienvenids-al-2017\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.nebrija.com\/medios\/nebrijaglobalcampus\/2017\/01\/10\/bienvenids-al-2017\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.nebrija.com\/medios\/nebrijaglobalcampus\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bienvenid@s al 2017\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.nebrija.com\/medios\/nebrijaglobalcampus\/#website\",\"url\":\"https:\/\/www.nebrija.com\/medios\/nebrijaglobalcampus\/\",\"name\":\"Global Campus Nebrija\",\"description\":\"Profesionales capaces de hacer que merezca la pena\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.nebrija.com\/medios\/nebrijaglobalcampus\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.nebrija.com\/medios\/nebrijaglobalcampus\/#\/schema\/person\/0fa46cb03c7e07b210c31383337aa6ee\",\"name\":\"mgarcisa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.nebrija.com\/medios\/nebrijaglobalcampus\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/03c5100e64e7f8981aa1450029b9aae2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/03c5100e64e7f8981aa1450029b9aae2?s=96&d=mm&r=g\",\"caption\":\"mgarcisa\"},\"url\":\"https:\/\/www.nebrija.com\/medios\/nebrijaglobalcampus\/author\/mgarcisa\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bienvenid@s al 2017 - Global Campus Nebrija","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.nebrija.com\/medios\/nebrijaglobalcampus\/2017\/01\/10\/bienvenids-al-2017\/","og_locale":"es_ES","og_type":"article","og_title":"Bienvenid@s al 2017 - Global Campus Nebrija","og_description":"Estrenamos calendario. 365 oportunidades para crecer, aprender, equivocarse, triunfar, retomar, decidir, cambiar, intentar&#8230; Todo est\u00e1 por hacer. Y m\u00e1s en el \u00e1mbito de la formaci\u00f3n y el aprendizaje: \u00abLos analfabetos del siglo XXI no ser\u00e1n aquellos que no sepan leer y escribir, sino aquellos que no sepan aprender, desaprender y reaprender\u00bb, Herbert Gerjuoy. &nbsp; El [&hellip;]","og_url":"https:\/\/www.nebrija.com\/medios\/nebrijaglobalcampus\/2017\/01\/10\/bienvenids-al-2017\/","og_site_name":"Global Campus Nebrija","article_published_time":"2017-01-10T08:25:29+00:00","og_image":[{"width":4584,"height":3690,"url":"https:\/\/www.nebrija.com\/medios\/nebrijaglobalcampus\/wp-content\/uploads\/sites\/31\/2017\/01\/shutterstock_538443043b.jpg","type":"image\/jpeg"}],"author":"mgarcisa","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"mgarcisa","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.nebrija.com\/medios\/nebrijaglobalcampus\/2017\/01\/10\/bienvenids-al-2017\/","url":"https:\/\/www.nebrija.com\/medios\/nebrijaglobalcampus\/2017\/01\/10\/bienvenids-al-2017\/","name":"Bienvenid@s al 2017 - Global Campus Nebrija","isPartOf":{"@id":"https:\/\/www.nebrija.com\/medios\/nebrijaglobalcampus\/#website"},"datePublished":"2017-01-10T08:25:29+00:00","dateModified":"2017-01-10T08:25:29+00:00","author":{"@id":"https:\/\/www.nebrija.com\/medios\/nebrijaglobalcampus\/#\/schema\/person\/0fa46cb03c7e07b210c31383337aa6ee"},"breadcrumb":{"@id":"https:\/\/www.nebrija.com\/medios\/nebrijaglobalcampus\/2017\/01\/10\/bienvenids-al-2017\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.nebrija.com\/medios\/nebrijaglobalcampus\/2017\/01\/10\/bienvenids-al-2017\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.nebrija.com\/medios\/nebrijaglobalcampus\/2017\/01\/10\/bienvenids-al-2017\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.nebrija.com\/medios\/nebrijaglobalcampus\/"},{"@type":"ListItem","position":2,"name":"Bienvenid@s al 2017"}]},{"@type":"WebSite","@id":"https:\/\/www.nebrija.com\/medios\/nebrijaglobalcampus\/#website","url":"https:\/\/www.nebrija.com\/medios\/nebrijaglobalcampus\/","name":"Global Campus Nebrija","description":"Profesionales capaces de hacer que merezca la pena","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.nebrija.com\/medios\/nebrijaglobalcampus\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.nebrija.com\/medios\/nebrijaglobalcampus\/#\/schema\/person\/0fa46cb03c7e07b210c31383337aa6ee","name":"mgarcisa","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.nebrija.com\/medios\/nebrijaglobalcampus\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/03c5100e64e7f8981aa1450029b9aae2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/03c5100e64e7f8981aa1450029b9aae2?s=96&d=mm&r=g","caption":"mgarcisa"},"url":"https:\/\/www.nebrija.com\/medios\/nebrijaglobalcampus\/author\/mgarcisa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.nebrija.com\/medios\/nebrijaglobalcampus\/wp-json\/wp\/v2\/posts\/1185"}],"collection":[{"href":"https:\/\/www.nebrija.com\/medios\/nebrijaglobalcampus\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.nebrija.com\/medios\/nebrijaglobalcampus\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.nebrija.com\/medios\/nebrijaglobalcampus\/wp-json\/wp\/v2\/users\/97"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nebrija.com\/medios\/nebrijaglobalcampus\/wp-json\/wp\/v2\/comments?post=1185"}],"version-history":[{"count":5,"href":"https:\/\/www.nebrija.com\/medios\/nebrijaglobalcampus\/wp-json\/wp\/v2\/posts\/1185\/revisions"}],"predecessor-version":[{"id":1198,"href":"https:\/\/www.nebrija.com\/medios\/nebrijaglobalcampus\/wp-json\/wp\/v2\/posts\/1185\/revisions\/1198"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.nebrija.com\/medios\/nebrijaglobalcampus\/wp-json\/wp\/v2\/media\/1191"}],"wp:attachment":[{"href":"https:\/\/www.nebrija.com\/medios\/nebrijaglobalcampus\/wp-json\/wp\/v2\/media?parent=1185"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.nebrija.com\/medios\/nebrijaglobalcampus\/wp-json\/wp\/v2\/categories?post=1185"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.nebrija.com\/medios\/nebrijaglobalcampus\/wp-json\/wp\/v2\/tags?post=1185"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}